{"id":34748,"date":"2022-02-02T11:15:05","date_gmt":"2022-02-02T11:15:05","guid":{"rendered":"http:\/\/citizenshiprightsafrica.org\/guinee-nzerekore-appel-aux-citoyens-a-obtenir-leur-acte-de-naissance-biometrique-a-la-mairie\/"},"modified":"2022-02-02T11:15:05","modified_gmt":"2022-02-02T11:15:05","slug":"guinee-nzerekore-appel-aux-citoyens-a-obtenir-leur-acte-de-naissance-biometrique-a-la-mairie","status":"publish","type":"post","link":"https:\/\/citizenshiprightsafrica.org\/en\/guinee-nzerekore-appel-aux-citoyens-a-obtenir-leur-acte-de-naissance-biometrique-a-la-mairie\/","title":{"rendered":"Guin\u00e9e: N\u2019Z\u00e9r\u00e9kor\u00e9, appel aux citoyens \u00e0 obtenir leur acte de naissance biom\u00e9trique \u00e0 la mairie"},"content":{"rendered":"<p>La d\u00e9livrance des actes de naissance biom\u00e9trique a d\u00e9marr\u00e9 en Guin\u00e9e. A N\u2019Nz\u00e9r\u00e9kor\u00e9, ces travaux se d\u00e9roulent \u00e0 l\u2019\u00e9tat civil de la mairie. Pour le moment pas d\u2019affluence. C\u2019est pourquoi le superviseur en charge des activistes, Boniface Dramou, invite les citoyens \u00e0 venir s\u2019acquitter de leur droit civique. \u00ab\u00a0<strong>Il y\u2019a deux semaines nous avons commenc\u00e9 des activit\u00e9s, mais la population n\u2019est pas suffisamment inform\u00e9e du d\u00e9marrage des travaux. Apr\u00e8s des actes biom\u00e9trique nous n\u2019aurons plus besoin des anciens actes de naissance.<\/strong><\/p>\n<p><a href=\"https:\/\/kalenews.org\/nzerekore-appel-aux-citoyens-a-obtenir-leur-acte-de-naissance-biometrique-a-la-mairie\/\">Lire la suite<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"La d\u00e9livrance des actes de naissance biom\u00e9trique a d\u00e9marr\u00e9 en Guin\u00e9e. A N\u2019Nz\u00e9r\u00e9kor\u00e9, ces travaux se d\u00e9roulent \u00e0 l\u2019\u00e9tat civil de la mairie. Pour le moment pas d\u2019affluence. C\u2019est pourquoi le superviseur en charge des activistes, Boniface Dramou, invite les citoyens \u00e0 venir s\u2019acquitter de leur droit civique. \u00ab\u00a0Il y\u2019a deux semaines nous avons commenc\u00e9 [&hellip;]","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-34748","post","type-post","status-publish","format-standard","hentry","category-uncategorized","region-guinea","region-west-africa","type-news-articles","item-year-683","item-theme-birth-registration","item-theme-identity-documents"],"acf":[],"_links":{"self":[{"href":"https:\/\/citizenshiprightsafrica.org\/en\/wp-json\/wp\/v2\/posts\/34748","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/citizenshiprightsafrica.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/citizenshiprightsafrica.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/citizenshiprightsafrica.org\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/citizenshiprightsafrica.org\/en\/wp-json\/wp\/v2\/comments?post=34748"}],"version-history":[{"count":0,"href":"https:\/\/citizenshiprightsafrica.org\/en\/wp-json\/wp\/v2\/posts\/34748\/revisions"}],"wp:attachment":[{"href":"https:\/\/citizenshiprightsafrica.org\/en\/wp-json\/wp\/v2\/media?parent=34748"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/citizenshiprightsafrica.org\/en\/wp-json\/wp\/v2\/categories?post=34748"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/citizenshiprightsafrica.org\/en\/wp-json\/wp\/v2\/tags?post=34748"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}