{"id":38258,"date":"2023-05-01T07:50:04","date_gmt":"2023-05-01T07:50:04","guid":{"rendered":"http:\/\/citizenshiprightsafrica.org\/congo-lutte-contre-lapatridie-locla-sensibilise-a-lenregistrement-des-naissances-a-brazzaville\/"},"modified":"2023-05-01T07:50:04","modified_gmt":"2023-05-01T07:50:04","slug":"congo-lutte-contre-lapatridie-locla-sensibilise-a-lenregistrement-des-naissances-a-brazzaville","status":"publish","type":"post","link":"https:\/\/citizenshiprightsafrica.org\/en\/congo-lutte-contre-lapatridie-locla-sensibilise-a-lenregistrement-des-naissances-a-brazzaville\/","title":{"rendered":"Congo: Lutte contre l\u2019apatridie : l\u2019Ocla sensibilise \u00e0 l\u2019enregistrement des naissances \u00e0 Brazzaville"},"content":{"rendered":"<p>La campagne s&#8217;inscrit dans le cadre des engagements pris par le gouvernement de la R\u00e9publique du Congo en mati\u00e8re de lutte contre l&#8217;apatridie sur l\u2019ensemble de son territoire. L\u2019initiative de cette organisation\u00a0vise la pr\u00e9vention de l&#8217;apatridie. Cette deuxi\u00e8me phase concerne tous les arrondissements de Brazzaville y compris l&#8217;\u00eele Mbamou. Ainsi, cette phase qui se d\u00e9roulera du 25 avril au 31 d\u00e9cembre\u00a0couvrira environ 100 000 m\u00e9nages dont les habitants sont de diff\u00e9rentes nationalit\u00e9s et sera coupl\u00e9e \u00e0 l&#8217;identification des personnes \u00e0 risque d&#8217;apatridie.<\/p>\n<p><a href=\"https:\/\/www.adiac-congo.com\/content\/lutte-contre-lapatridie-locla-sensibilise-lenregistrement-des-naissances-brazzaville-147811\">Lire la suite<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"La campagne s&#8217;inscrit dans le cadre des engagements pris par le gouvernement de la R\u00e9publique du Congo en mati\u00e8re de lutte contre l&#8217;apatridie sur l\u2019ensemble de son territoire. L\u2019initiative de cette organisation\u00a0vise la pr\u00e9vention de l&#8217;apatridie. Cette deuxi\u00e8me phase concerne tous les arrondissements de Brazzaville y compris l&#8217;\u00eele Mbamou. Ainsi, cette phase qui se d\u00e9roulera [&hellip;]","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[499,1],"tags":[],"class_list":["post-38258","post","type-post","status-publish","format-standard","hentry","category-non-classifiee","category-uncategorized","region-afrique-centrale","region-republique-du-congo","type-articles-de-presse","item-year-691","item-theme-apatridie"],"acf":[],"_links":{"self":[{"href":"https:\/\/citizenshiprightsafrica.org\/en\/wp-json\/wp\/v2\/posts\/38258","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/citizenshiprightsafrica.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/citizenshiprightsafrica.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/citizenshiprightsafrica.org\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/citizenshiprightsafrica.org\/en\/wp-json\/wp\/v2\/comments?post=38258"}],"version-history":[{"count":0,"href":"https:\/\/citizenshiprightsafrica.org\/en\/wp-json\/wp\/v2\/posts\/38258\/revisions"}],"wp:attachment":[{"href":"https:\/\/citizenshiprightsafrica.org\/en\/wp-json\/wp\/v2\/media?parent=38258"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/citizenshiprightsafrica.org\/en\/wp-json\/wp\/v2\/categories?post=38258"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/citizenshiprightsafrica.org\/en\/wp-json\/wp\/v2\/tags?post=38258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}